{"id":972,"date":"2022-03-23T08:45:29","date_gmt":"2022-03-23T08:45:29","guid":{"rendered":"https:\/\/www.stellamarisbeach.it\/vacanze-sicure\/"},"modified":"2022-04-12T14:08:06","modified_gmt":"2022-04-12T14:08:06","slug":"vacanze-sicure","status":"publish","type":"page","link":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/","title":{"rendered":"Vacanze Sicure"},"content":{"rendered":"<p>Ci teniamo alla tua serenit\u00e0 durante le vacanze o le giornate di riposo che trascorrerai da noi a Sottomarina. Per questo, in collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure, che ci permette di dare assistenza ai nostri ospiti, in modo immediato e professionale, per ogni problema di salute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci teniamo alla tua serenit\u00e0 durante le vacanze o le giornate di riposo che trascorrerai da noi a Sottomarina. Per questo, in collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure, che ci permette di dare assistenza ai nostri ospiti, in modo immediato e professionale, per ogni problema di salute.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vacanze Sicure | Stella Maris<\/title>\n<meta name=\"description\" content=\"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacanze Sicure | Stella Maris\" \/>\n<meta property=\"og:description\" content=\"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/\" \/>\n<meta property=\"og:site_name\" content=\"Stella Maris\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T14:08:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.stellamarisbeach.it\/#organization\",\"name\":\"StellaMaris\",\"url\":\"https:\/\/www.stellamarisbeach.it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.stellamarisbeach.it\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.stellamarisbeach.it\/wp-content\/uploads\/2024\/02\/logo-stella-maris-1.png\",\"contentUrl\":\"https:\/\/www.stellamarisbeach.it\/wp-content\/uploads\/2024\/02\/logo-stella-maris-1.png\",\"width\":842,\"height\":595,\"caption\":\"StellaMaris\"},\"image\":{\"@id\":\"https:\/\/www.stellamarisbeach.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.stellamarisbeach.it\/#website\",\"url\":\"https:\/\/www.stellamarisbeach.it\/\",\"name\":\"Stella Maris\",\"description\":\"My Sand Club\",\"publisher\":{\"@id\":\"https:\/\/www.stellamarisbeach.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.stellamarisbeach.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#webpage\",\"url\":\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/\",\"name\":\"Vacanze Sicure | Stella Maris\",\"isPartOf\":{\"@id\":\"https:\/\/www.stellamarisbeach.it\/#website\"},\"datePublished\":\"2022-03-23T08:45:29+00:00\",\"dateModified\":\"2022-04-12T14:08:06+00:00\",\"description\":\"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.stellamarisbeach.it\/homepage\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacanze Sicure\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacanze Sicure | Stella Maris","description":"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/","og_locale":"en_US","og_type":"article","og_title":"Vacanze Sicure | Stella Maris","og_description":"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.","og_url":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/","og_site_name":"Stella Maris","article_modified_time":"2022-04-12T14:08:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.stellamarisbeach.it\/#organization","name":"StellaMaris","url":"https:\/\/www.stellamarisbeach.it\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.stellamarisbeach.it\/#logo","inLanguage":"en-US","url":"https:\/\/www.stellamarisbeach.it\/wp-content\/uploads\/2024\/02\/logo-stella-maris-1.png","contentUrl":"https:\/\/www.stellamarisbeach.it\/wp-content\/uploads\/2024\/02\/logo-stella-maris-1.png","width":842,"height":595,"caption":"StellaMaris"},"image":{"@id":"https:\/\/www.stellamarisbeach.it\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.stellamarisbeach.it\/#website","url":"https:\/\/www.stellamarisbeach.it\/","name":"Stella Maris","description":"My Sand Club","publisher":{"@id":"https:\/\/www.stellamarisbeach.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stellamarisbeach.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#webpage","url":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/","name":"Vacanze Sicure | Stella Maris","isPartOf":{"@id":"https:\/\/www.stellamarisbeach.it\/#website"},"datePublished":"2022-03-23T08:45:29+00:00","dateModified":"2022-04-12T14:08:06+00:00","description":"In collaborazione con l\u2019Ussl3 Serenissima e l\u2019Ospedale di Chioggia abbiamo siglato un accordo Vacanze Sicure per gli ospiti di StellaMaris.","breadcrumb":{"@id":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.stellamarisbeach.it\/en\/vacanze-sicure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stellamarisbeach.it\/homepage\/?lang=en"},{"@type":"ListItem","position":2,"name":"Vacanze Sicure"}]}]}},"_links":{"self":[{"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/pages\/972"}],"collection":[{"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/comments?post=972"}],"version-history":[{"count":1,"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/pages\/972\/revisions"}],"predecessor-version":[{"id":973,"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/pages\/972\/revisions\/973"}],"wp:attachment":[{"href":"https:\/\/www.stellamarisbeach.it\/en\/wp-json\/wp\/v2\/media?parent=972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}